{"id":3415,"date":"2021-12-17T14:52:46","date_gmt":"2021-12-17T07:52:46","guid":{"rendered":"https:\/\/osterberg-quality.vn\/?post_type=chia-se-cong-thuc&#038;p=3415"},"modified":"2022-05-30T13:52:48","modified_gmt":"2022-05-30T06:52:48","slug":"how-to-drink-cocktail","status":"publish","type":"chia-se-cong-thuc","link":"https:\/\/osterberg-quality.vn\/en\/chia-se-cong-thuc\/how-to-drink-cocktail\/","title":{"rendered":"How to drink Cocktail"},"content":{"rendered":"<p>The first taste is the burst of rum. Then the fruity aroma is gently enjoyed. But how to enjoy this drink perfectly? Look at its color. Try it!<\/p>","protected":false},"featured_media":4215,"template":"","meta":{"site-sidebar-layout":"default","site-content-layout":"default","ast-global-header-display":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","theme-transparent-header-meta":"default","adv-header-id-meta":"","stick-header-meta":"default","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":""},"chuyen-muc-chia-se-cong-thuc":[49],"class_list":["post-3415","chia-se-cong-thuc","type-chia-se-cong-thuc","status-publish","has-post-thumbnail","hentry","chuyen-muc-chia-se-cong-thuc-mon-nuoc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>How to drink Cocktail - Osterberg | Leading provider of fruit-based beverage and bakery ingredients.<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/osterberg-quality.vn\/en\/chia-se-cong-thuc\/how-to-drink-cocktail\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"How to drink Cocktail - Osterberg | Leading provider of fruit-based beverage and bakery ingredients.\" \/>\n<meta property=\"og:description\" content=\"B\u00f9ng ch\u00e1y b\u1edfi th\u00e0nh ph\u1ea7n r\u01b0\u1ee3u rum l\u00e0 c\u1ea3m nh\u1eadn \u0111\u1ea7u ti\u00ean. Sau \u0111\u00f3 nh\u1eb9 nh\u00e0ng t\u1eadn h\u01b0\u1edfng m\u00f9i v\u1ecb tr\u00e1i c\u00e2y th\u01a1m l\u1ef1ng. Nh\u01b0ng l\u00e0m sao th\u01b0\u1edfng th\u1ee9c h\u1ebft m\u00f3n u\u1ed1ng n\u00e0y m\u1ed9t c\u00e1ch ho\u00e0n h\u1ea3o? H\u00e3y nh\u00ecn m\u00e0u s\u1eafc c\u1ee7a n\u00f3. Th\u1eed nh\u00e9!\" \/>\n<meta property=\"og:url\" content=\"https:\/\/osterberg-quality.vn\/en\/chia-se-cong-thuc\/how-to-drink-cocktail\/\" \/>\n<meta property=\"og:site_name\" content=\"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.\" \/>\n<meta property=\"article:modified_time\" content=\"2022-05-30T06:52:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png\" \/>\n\t<meta property=\"og:image:width\" content=\"900\" \/>\n\t<meta property=\"og:image:height\" content=\"900\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/\",\"url\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/\",\"name\":\"How to drink Cocktail - Osterberg | Leading provider of fruit-based beverage and bakery ingredients.\",\"isPartOf\":{\"@id\":\"https:\/\/osterberg-quality.vn\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png\",\"datePublished\":\"2021-12-17T07:52:46+00:00\",\"dateModified\":\"2022-05-30T06:52:48+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#primaryimage\",\"url\":\"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png\",\"contentUrl\":\"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png\",\"width\":900,\"height\":900},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Trang ch\u1ee7\",\"item\":\"https:\/\/osterberg-quality.vn\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Chia s\u1ebb c\u00f4ng th\u1ee9c\",\"item\":\"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"How to drink Cocktail\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/osterberg-quality.vn\/en\/#website\",\"url\":\"https:\/\/osterberg-quality.vn\/en\/\",\"name\":\"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.\",\"description\":\"Leading provider of fruit-based beverage and bakery ingredients.\",\"publisher\":{\"@id\":\"https:\/\/osterberg-quality.vn\/en\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/osterberg-quality.vn\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/osterberg-quality.vn\/en\/#organization\",\"name\":\"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.\",\"url\":\"https:\/\/osterberg-quality.vn\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/osterberg-quality.vn\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/10\/logo.png\",\"contentUrl\":\"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/10\/logo.png\",\"width\":301,\"height\":167,\"caption\":\"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.\"},\"image\":{\"@id\":\"https:\/\/osterberg-quality.vn\/en\/#\/schema\/logo\/image\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"How to drink Cocktail - Osterberg | Leading provider of fruit-based beverage and bakery ingredients.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/osterberg-quality.vn\/en\/chia-se-cong-thuc\/how-to-drink-cocktail\/","og_locale":"en_US","og_type":"article","og_title":"How to drink Cocktail - Osterberg | Leading provider of fruit-based beverage and bakery ingredients.","og_description":"B\u00f9ng ch\u00e1y b\u1edfi th\u00e0nh ph\u1ea7n r\u01b0\u1ee3u rum l\u00e0 c\u1ea3m nh\u1eadn \u0111\u1ea7u ti\u00ean. Sau \u0111\u00f3 nh\u1eb9 nh\u00e0ng t\u1eadn h\u01b0\u1edfng m\u00f9i v\u1ecb tr\u00e1i c\u00e2y th\u01a1m l\u1ef1ng. Nh\u01b0ng l\u00e0m sao th\u01b0\u1edfng th\u1ee9c h\u1ebft m\u00f3n u\u1ed1ng n\u00e0y m\u1ed9t c\u00e1ch ho\u00e0n h\u1ea3o? H\u00e3y nh\u00ecn m\u00e0u s\u1eafc c\u1ee7a n\u00f3. Th\u1eed nh\u00e9!","og_url":"https:\/\/osterberg-quality.vn\/en\/chia-se-cong-thuc\/how-to-drink-cocktail\/","og_site_name":"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.","article_modified_time":"2022-05-30T06:52:48+00:00","og_image":[{"width":900,"height":900,"url":"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png","type":"image\/png"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/","url":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/","name":"How to drink Cocktail - Osterberg | Leading provider of fruit-based beverage and bakery ingredients.","isPartOf":{"@id":"https:\/\/osterberg-quality.vn\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#primaryimage"},"image":{"@id":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#primaryimage"},"thumbnailUrl":"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png","datePublished":"2021-12-17T07:52:46+00:00","dateModified":"2022-05-30T06:52:48+00:00","breadcrumb":{"@id":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#primaryimage","url":"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png","contentUrl":"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/12\/osterberg-How-To-Drink-cocktail.png","width":900,"height":900},{"@type":"BreadcrumbList","@id":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/how-to-drink-cocktail\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Trang ch\u1ee7","item":"https:\/\/osterberg-quality.vn\/"},{"@type":"ListItem","position":2,"name":"Chia s\u1ebb c\u00f4ng th\u1ee9c","item":"https:\/\/osterberg-quality.vn\/chia-se-cong-thuc\/"},{"@type":"ListItem","position":3,"name":"How to drink Cocktail"}]},{"@type":"WebSite","@id":"https:\/\/osterberg-quality.vn\/en\/#website","url":"https:\/\/osterberg-quality.vn\/en\/","name":"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.","description":"Leading provider of fruit-based beverage and bakery ingredients.","publisher":{"@id":"https:\/\/osterberg-quality.vn\/en\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/osterberg-quality.vn\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/osterberg-quality.vn\/en\/#organization","name":"Osterberg | Leading provider of fruit-based beverage and bakery ingredients.","url":"https:\/\/osterberg-quality.vn\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/osterberg-quality.vn\/en\/#\/schema\/logo\/image\/","url":"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/10\/logo.png","contentUrl":"https:\/\/osterberg-quality.vn\/wp-content\/uploads\/2021\/10\/logo.png","width":301,"height":167,"caption":"Osterberg | Leading provider of fruit-based beverage and bakery ingredients."},"image":{"@id":"https:\/\/osterberg-quality.vn\/en\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/chia-se-cong-thuc\/3415","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/chia-se-cong-thuc"}],"about":[{"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/types\/chia-se-cong-thuc"}],"version-history":[{"count":0,"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/chia-se-cong-thuc\/3415\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/media\/4215"}],"wp:attachment":[{"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/media?parent=3415"}],"wp:term":[{"taxonomy":"chuyen-muc-chia-se-cong-thuc","embeddable":true,"href":"https:\/\/osterberg-quality.vn\/en\/wp-json\/wp\/v2\/chuyen-muc-chia-se-cong-thuc?post=3415"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}